{"id":248514,"date":"2023-12-11T15:58:48","date_gmt":"2023-12-11T14:58:48","guid":{"rendered":"https:\/\/ellegi.com\/?page_id=248514"},"modified":"2024-01-17T16:27:40","modified_gmt":"2024-01-17T15:27:40","slug":"whistleblowing","status":"publish","type":"page","link":"https:\/\/ellegi.com\/it\/whistleblowing\/","title":{"rendered":"Whistleblowing"},"content":{"rendered":"[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Contatti &#8211; titolo principale&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#fcbd1b&#8221; custom_padding=&#8221;111px||45px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;500px&#8221; width_tablet=&#8221;400px&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|tablet&#8221; overflow-x=&#8221;hidden&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;c4731467-a79e-4ec1-9cf3-7b556cf8a39c&#8221; global_colors_info=&#8221;{}&#8221;]\n<h2>06<\/h2>\n<p><span><\/span><\/p>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;96e9bf89-a87f-457c-b304-aadbf360ab1a&#8221; global_colors_info=&#8221;{}&#8221;]\n<h3><span>La nostra informativa<\/span><\/h3>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;684ae210-dce5-4063-8021-75b508bd5af1&#8243; global_colors_info=&#8221;{}&#8221;]\n<h1>Whistleblowing<\/h1>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;80%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;_initial&#8221; text_text_color=&#8221;#333333&#8243; ul_text_color=&#8221;#333333&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<h2>SEGNALAZIONI WHISTLEBLOWING<\/h2>\n<p>In recepimento del Decreto Legislativo 10 marzo 2023, n. 24, Ellegi S.p.A. si \u00e8 dotata dei prescritti canali per la ricezione e la gestione delle segnalazioni denominate \u201cwhistleblowing\u201d.<\/p>\n<h3>CHI PU\u00d2 SEGNALARE?<\/h3>\n<ul>\n<li>I soci e le persone con funzioni di amministrazione, direzione, controllo, vigilanza o rappresentanza, anche qualora tali funzioni siano esercitate in via di mero fatto, presso Ellegi S.p.A.;<\/li>\n<li>I lavoratori subordinati, i tirocinanti, i lavoratori autonomi, i liberi professionisti ed i consulenti che prestano la propria opera presso Ellegi S.p.A.;<\/li>\n<li>Soggetti che hanno rivestito i ruoli sopra indicati in passato, se le informazioni sulle violazioni sono state acquisite nel corso del rapporto e soggetti con i quali il rapporto non \u00e8 ancora sorto \u2013 per esempio i candidati alla selezione del personale o i dipendenti durante il periodo di prova.<\/li>\n<\/ul>\n<h3>AMBITI DI POTENZIALE SEGNALAZIONE<\/h3>\n<p>L\u2019elenco \u00e8 molto articolato e complesso. Per completezza si rimanda al D.Lgs. 24\/2023<sup style=\"font-size: 14px;\">1<\/sup>.<\/p>\n<h3><\/h3>\n<h3>I CANALI DI SEGNALAZIONE<\/h3>\n[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;30px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.8em&#8221; body_line_height=&#8221;1.3em&#8221; module_alignment=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>Numero verde<\/p>\n<p><a href=\"tel:800231670\">800 &#8211; 231 &#8211; 670<\/a><\/p>\n<p><span style=\"font-size: 14px;\">La chiamata \u00e8 registrata<\/span><\/p>\n[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;30px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.8em&#8221; body_line_height=&#8221;1.3em&#8221; module_alignment=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>Indirizzo di posta elettronica<\/p>\n<p><a href=\"mailto:ellegispa_whistleblowing@complegal.it\">ellegispa_whistleblowing@complegal.it<\/a><sup style=\"font-size: 14px;\">2<\/sup><\/p>\n[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe065;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;30px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.8em&#8221; body_line_height=&#8221;1.3em&#8221; module_alignment=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>Il segnalante ha altres\u00ec il diritto di richiedere un incontro diretto con un professionista esterno all\u2019azienda, che gestisce il canale per conferire la segnalazione in un colloquio riservato; sar\u00e0 sufficiente farne richiesta mediante uno dei due canali sopra indicati, lasciando un recapito per essere contattati.<\/p>\n[\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;_initial&#8221; text_text_color=&#8221;#333333&#8243; ul_text_color=&#8221;#333333&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>&nbsp;<\/p>\n<h3><\/h3>\n<h3>MATERIALE INFORMATIVO:<\/h3>\n[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf019;||fa||900&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;30px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.8em&#8221; body_line_height=&#8221;1.3em&#8221; module_alignment=&#8221;left&#8221; link_option_url=&#8221;https:\/\/ellegi.com\/wp-content\/uploads\/2024\/01\/INFORMATIVA-TRATTAMENTO-DATI-PERSONALI-DEI-SEGNALANTI.pdf&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; link_option_url_new_window=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;]\n<p>Informativa trattamento dati personali dei segnalanti<\/p>\n[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf019;||fa||900&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;30px&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.8em&#8221; body_line_height=&#8221;1.3em&#8221; module_alignment=&#8221;left&#8221; link_option_url=&#8221;https:\/\/ellegi.com\/wp-content\/uploads\/2024\/01\/PROCEDURA-WHISTLEBLOWING.pdf&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; link_option_url_new_window=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;]\n<p>Procedura whistleblowing<\/p>\n[\/et_pb_blurb][et_pb_divider color=&#8221;#FCBD1B&#8221; divider_weight=&#8221;6px&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; width=&#8221;45px&#8221; custom_padding=&#8221;30px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;_initial&#8221; text_text_color=&#8221;#333333&#8243; ul_text_color=&#8221;#333333&#8243; ol_font_size=&#8221;15px&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]\n<ol>\n<li>In linea generale sono potenzialmente oggetto di segnalazione le violazioni di disposizioni normative dell\u2019Unione europea che ledono l\u2019interesse pubblico o l\u2019integrit\u00e0 della Societ\u00e0, di cui il segnalante sia venuto a conoscenza nel contesto lavorativo, consistenti in: condotte illecite rilevanti ai sensi del Decreto 231\/2001 o violazioni del Modello 231 se adottato; illeciti che rientrano nell&#8217;;ambito di applicazione degli atti dell&#8217;Unione europea o nazionali ovvero degli atti nazionali che costituiscono attuazione degli atti dell&#8217;Unione europea in materia di appalti pubblici; servizi, prodotti e mercati finanziari e prevenzione del riciclaggio e del finanziamento del terrorismo; sicurezza e conformit\u00e0 dei prodotti; sicurezza dei trasporti; tutela dell&#8217;ambiente; radioprotezione e sicurezza nucleare; sicurezza degli alimenti e dei mangimi e salute e benessere degli animali; salute pubblica; protezione dei consumatori; tutela della vita privata e protezione dei dati personali e sicurezza delle reti e dei sistemi informativi; atti od omissioni che ledono gli interessi finanziari dell&#8217;Unione europea di cui all\u2019art. 325 del Trattato sul Funzionamento dell\u2019Unione Europea; atti od omissioni riguardanti il mercato interno, di cui all\u2019art. 26, par. 2, T.F.U.E. (comprese le violazioni in materia di concorrenza e di aiuti di Stato e quelle in materia di imposta sulle societ\u00e0); atti o comportamenti che, pur non integrando un illecito, vanificano l&#8217;oggetto o la finalit\u00e0 delle disposizioni di cui agli atti dell&#8217;Unione nei settori sopra indicati.<\/li>\n<li>A tutela della riservatezza del Segnalante, qualora lo stesso desideri non rilasciare il consenso al disvelamento della sua identit\u00e0, le segnalazioni scritte devono essere inviate da caselle di posta elettronica personali, non aziendali (pertanto, occorre evitare di inviare segnalazioni da caselle su dominio aziendale).<\/li>\n<\/ol>\n<div class=\"page-title-holder\"><\/div>\n<div class=\"two_third\">\n<p>&nbsp;<\/p>\n<\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>06 La nostra informativaWhistleblowingSEGNALAZIONI WHISTLEBLOWING In recepimento del Decreto Legislativo 10 marzo 2023, n. 24, Ellegi S.p.A. si \u00e8 dotata dei prescritti canali per la ricezione e la gestione delle segnalazioni denominate \u201cwhistleblowing\u201d. CHI PU\u00d2 SEGNALARE? I soci e le persone con funzioni di amministrazione, direzione, controllo, vigilanza o rappresentanza, anche qualora tali funzioni siano [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<h3>I \u2013 INFORMAZIONI RELATIVE ALLA PRIVACY POLICY DEL SITO<\/h3>\nIn questa sezione sono contenute le informazioni relative alle modalit\u00e0 di gestione di Sito web Nida\u2019s in riferimento al trattamento dei dati degli utenti di Sito web Nida\u2019s.\nLa presente informativa ha valore anche ai fini dell\u2019 art. 13 del D.Lgs. n. 196\/2003, Codice in materia di protezione dei dati personali, e ai fini dell\u2019articolo 13 del Regolamento UE n. 2016\/679, relativo alla protezione delle persone fisiche con riguardo al trattamento dei dati personali nonch\u00e9 alla libera circolazione di tali dati, per i soggetti che interagiscono con Sito web Nida\u2019s ed \u00e8 raggiungibile all\u2019indirizzo corrispondente alla pagina iniziale: www.nidas.it\nL\u2019informativa \u00e8 resa solo per Sito web Nida\u2019s e non anche per altri siti web eventualmente consultati dall\u2019utente tramite link in esso contenuti.\nScopo del presente documento \u00e8 fornire indicazioni circa le modalit\u00e0, i tempi e la natura delle informazioni che i titolari del trattamento devono fornire agli utenti al momento della connessione alle pagine web di Sito web Nida\u2019s, indipendentemente dagli scopi del collegamento stesso, secondo la legislazione Italiana ed Europea.\nL\u2019informativa pu\u00f2 subire modifiche a causa dell\u2019introduzione di nuove norme al riguardo, si invita pertanto l\u2019utente a controllare periodicamente la presente pagina.\nSe l\u2019utente ha meno di 16 anni, ai sensi dell\u2019art.8, c.1 regolamento UE 2016\/679, dovr\u00e0 legittimare il suo consenso attraverso l\u2019autorizzazione dei genitori o di chi ne fa le veci.\n<h3>II \u2013 TRATTAMENTO DEI DATI<\/h3>\n<h4>1 \u2013 Titolare dei Dati<\/h4>\nIl titolare del trattamento \u00e8 la persona fisica o giuridica, l\u2019autorit\u00e0 pubblica, il servizio o altro organismo che, singolarmente o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento di dati personali. Si occupa anche dei profili sulla sicurezza.\nRelativamente al presente sito web il titolare del trattamento \u00e8: Nida Studios srl, e per ogni chiarimento o esercizio dei diritti dell\u2019utente potr\u00e0 contattarlo al seguente indirizzo mail: info@nidas.it.\n<h4>2 \u2013 Responsabile del trattamento dati<\/h4>\nIl responsabile del trattamento \u00e8 la persona fisica o giuridica, l\u2019autorit\u00e0 pubblica, il servizio o altro organismo che tratta dati personali per conto del titolare del trattamento.\nAi sensi dell\u2019articolo 28 del regolamento UE n. 2016\/679, su nomina del titolare del dati, il responsabile del trattamento dei dati del sito Sito web Nida\u2019s \u00e8: Nicola Aggogeri.\n<h4>3 \u2013 Luogo trattamento dati<\/h4>\nIl trattamento dei dati generato dall\u2019utilizzo di Sito web Nida\u2019s avviene presso Borgo Pietro Wuhrer, 123 Brescia.\nIn caso di necessit\u00e0, i dati connessi al servizio newsletter possono essere trattati dal responsabile del trattamento o soggetti da esso incaricati a tal fine presso la relativa sede.\n<h3>III\u2013 COOKIES<\/h3>\n<h4>1 \u2013 Tipo di Cookies<\/h4>\nIl sito Sito web Nida\u2019s utilizza cookies per rendere l\u2019esperienza di navigazione dell\u2019utente pi\u00f9 facile ed intuitiva: i cookies sono piccole stringhe di testo utilizzate per memorizzare alcune informazioni che possono riguardare l\u2019utente, le sue preferenze o il dispositivo di accesso a Internet (computer, tablet o cellulare) e vengono utilizzate principalmente per adeguare il funzionamento del sito alle aspettative dell\u2019utente, offrendo un\u2019esperienza di navigazione pi\u00f9 personalizzata e memorizzando le scelte effettuate in precedenza.\nUn cookie consiste in un ridotto insieme di dati trasferiti al browser dell\u2019utente da un server web e pu\u00f2 essere letto unicamente dal server che ha effettuato il trasferimento. Non si tratta di codice eseguibile e non trasmette virus.\nI cookies non registrano alcuna informazione personale e gli eventuali dati identificabili non verranno memorizzati. Se si desidera, \u00e8 possibile impedire il salvataggio di alcuni o tutti i cookie. Tuttavia, in questo caso l\u2019utilizzo del sito e dei servizi offerti potrebbe risultarne compromesso. Per procedere senza modificare le opzioni relative ai cookies \u00e8 sufficiente continuare con la navigazione.\nDi seguito le tipologie di cookies di cui il sito fa uso:\n<h4>2 \u2013 Cookies tecnici<\/h4>\nCi sono numerose tecnologie usate per conservare informazioni nel computer dell\u2019utente, che poi vengono raccolte dai siti. Tra queste la pi\u00f9 conosciuta e utilizzata \u00e8 quella dei cookies HTML. Essi servono per la navigazione e per facilitare l\u2019accesso e la fruizione del sito da parte dell\u2019utente. Sono necessari alla trasmissione di comunicazioni su rete elettronica ovvero al fornitore per erogare il servizio richiesto dal cliente.\nLe impostazioni per gestire o disattivare i cookies possono variare a seconda del browser internet utilizzato. Ad ogni modo, l\u2019utente pu\u00f2 gestire o richiedere la disattivazione generale o la cancellazione dei cookies, modificando le impostazioni del proprio browser internet. Tale disattivazione pu\u00f2 rallentare o impedire l\u2019accesso ad alcune parti del sito.\nL\u2019uso di cookies tecnici consente la fruizione sicura ed efficiente del sito.\nI cookies che vengono inseriti nel browser e ritrasmessi mediante Google Analytics o tramite il servizio statistiche di blogger o similari sono tecnici solo se utilizzati a fini di ottimizzazione del sito direttamente dal titolare del sito stesso, che potr\u00e0 raccogliere informazioni in forma aggregata sul numero degli utenti e su come questi visitano il sito. A queste condizioni, per i cookies analytics valgono le stesse regole, in tema di informativa e consenso, previste per i cookies tecnici.\nDal punto di vista della durata si possono distinguere cookies temporanei di sessione che si cancellano automaticamente al termine della sessione di navigazione e servono per identificare l\u2019utente e quindi evitare il login ad ogni pagina visitata e quelli permanenti che restano attivi nel pc fino a scadenza o cancellazione da parte dell\u2019utente.\nPotranno essere installati cookies di sessione al fine di consentire l\u2019accesso e la permanenza nell\u2019area riservata del portale come utente autenticato.\nEssi non vengono memorizzati in modo persistente ma esclusivamente per la durata della navigazione fino alla chiusura del browser e svaniscono con la chiusura dello stesso. Il loro uso \u00e8 strettamente limitato alla trasmissione di identificativi di sessione costituiti da numeri casuali generati dal server necessari per consentire l\u2019esplorazione sicura ed efficiente del sito.\n<h4>3 \u2013 Cookies di terze parti<\/h4>\nIn relazione alla provenienza si distinguono i cookies inviati al browser direttamente dal sito che si sta visitando e quelli di terze parti inviati al computer da altri siti e non da quello che si sta visitando.\nI cookies permanenti sono spesso cookies di terze parti.\nLa maggior parte dei cookies di terze parti \u00e8 costituita da cookies di tracciamento usati per individuare il comportamento online, capire gli interessi e quindi personalizzare le proposte pubblicitarie per gli utenti.\nPotranno essere installati cookies di terze parti analitici. Essi sono inviati da domini di predette terze parti esterni al sito.\nI cookies analitici di terze parti sono impiegati per rilevare informazioni sul comportamento degli utenti su Sito web Nida\u2019s. La rilevazione avviene in forma anonima, al fine di monitorare le prestazioni e migliorare l\u2019usabilit\u00e0 del sito. I cookies di profilazione di terze parti sono utilizzati per creare profili relativi agli utenti, al fine di proporre messaggi pubblicitari in linea con le scelte manifestate dagli utenti medesimi.\nL\u2019utilizzo di questi cookies \u00e8 disciplinato dalle regole predisposte dalle terze parti medesime, pertanto, si invitano gli utenti a prendere visione delle informative privacy e delle indicazioni per gestire o disabilitare i cookies pubblicate nelle relative pagine web.\n<h4>4 \u2013 Cookies di profilazione<\/h4>\nSono cookie di profilazione quelli a creare profili relativi all\u2019utente e vengono utilizzati al fine di inviare messaggi pubblicitari in linea con le preferenze manifestate dallo stesso nell\u2019ambito della navigazione in rete.\nQuando si utilizzeranno questi tipi di cookies l\u2019utente dovr\u00e0 dare un consenso esplicito.\nSi applicher\u00e0 l\u2019articolo 22 del Regolamento UE 2016\/679 e l\u2019articolo 122 del Codice in materia di protezione dei dati.\n<h3>IV \u2013 DATI TRATTATI<\/h3>\n<h4>1 \u2013 Modalit\u00e0 trattamento dati<\/h4>\nCome tutti i siti web anche il presente sito fa uso di log files nei quali vengono conservate informazioni raccolte in maniera automatizzata durante le visite degli utenti. Le informazioni raccolte potrebbero essere le seguenti:\n<ul>\n \t<li>indirizzo internet protocol (IP);<\/li>\n \t<li>tipo di browser e parametri del dispositivo usato per connettersi al sito;<\/li>\n \t<li>nome dell\u2019internet service provider (ISP);<\/li>\n \t<li>data e orario di visita;<\/li>\n \t<li>pagina web di provenienza del visitatore (referral) e di uscita;<\/li>\n \t<li>eventualmente il numero di click.<\/li>\n<\/ul>\nLe suddette informazioni sono trattate in forma automatizzata e raccolte in forma esclusivamente aggregata al fine di verificare il corretto funzionamento del sito, e per motivi di sicurezza. Tali informazioni saranno trattate in base ai legittimi interessi del titolare.\nA fini di sicurezza (filtri antispam, firewall, rilevazione virus), i dati registrati automaticamente possono eventualmente comprendere anche dati personali come l\u2019indirizzo Ip, che potrebbe essere utilizzato, conformemente alle leggi vigenti in materia, al fine di bloccare tentativi di danneggiamento al sito medesimo o di recare danno ad altri utenti, o comunque attivit\u00e0 dannose o costituenti reato. Tali dati non sono mai utilizzati per l\u2019identificazione o la profilazione dell\u2019utente, ma solo a fini di tutela del sito e dei suoi utenti, tali informazioni saranno trattate in base ai legittimi interessi del titolare.\nQualora il sito consenta l\u2019inserimento di commenti, oppure in caso di specifici servizi richiesti dall\u2019utente, ivi compresi la possibilit\u00e0 di inviare il Curriculum Vitae per un eventuale rapporto lavorativo, il sito rileva automaticamente e registra alcuni dati identificativi dell\u2019utente, compreso l\u2019indirizzo mail. Tali dati si intendono volontariamente forniti dall\u2019utente al momento della richiesta di erogazione del servizio. Inserendo un commento o altra informazione l\u2019utente accetta espressamente l\u2019informativa privacy, e in particolare acconsente che i contenuti inseriti siano liberamente diffusi anche a terzi. I dati ricevuti verranno utilizzati esclusivamente per l\u2019erogazione del servizio richiesto e per il solo tempo necessario per la fornitura del servizio.\nLe informazioni che gli utenti del sito riterranno di rendere pubbliche tramite i servizi e gli strumenti messi a disposizione degli stessi, sono fornite dall\u2019utente consapevolmente e volontariamente, esentando il presente sito da qualsiasi responsabilit\u00e0 in merito ad eventuali violazioni delle leggi. Spetta all\u2019utente verificare di avere i permessi per l\u2019immissione di dati personali di terzi o di contenuti tutelati dalle norme nazionali ed internazionali.\n<h4>2 \u2013 Finalit\u00e0 del trattamento dati<\/h4>\nI dati raccolti dal sito durante il suo funzionamento sono utilizzati esclusivamente per le finalit\u00e0 sopra indicate e conservati per il tempo strettamente necessario a svolgere le attivit\u00e0 precisate, e comunque non oltre 10 anni.\nI dati utilizzati a fini di sicurezza (blocco tentativi di danneggiamento del sito) sono conservati per il tempo strettamente necessario al raggiungimento del fine anteriormente indicato.\n<h4>3 \u2013 Dati forniti dall\u2019utente<\/h4>\nCome sopra indicato, l\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva.\nSpecifiche informative di sintesi verranno progressivamente riportate o visualizzate nelle pagine del sito predisposte per particolari servizi a richiesta.\n<h4>4 \u2013 Supporto nella configurazione del proprio browser<\/h4>\nL\u2019utente pu\u00f2 gestire i cookie anche attraverso le impostazioni del suo browser. Tuttavia, cancellando i cookies dal browser potrebbe rimuovere le preferenze che ha impostato per il sito.\nPer ulteriori informazioni e supporto \u00e8 possibile anche visitare la pagina di aiuto specifica del web browser che si sta utilizzando:\n<ul>\n \t<li>Internet Explorer: http:\/\/windows.microsoft.com\/en-us\/windows-vista\/block-or-allow-cookies<\/li>\n \t<li>Firefox: https:\/\/support.mozilla.org\/en-us\/kb\/enable-and-disable-cookies-website-preferences<\/li>\n \t<li>Safari: http:\/\/www.apple.com\/legal\/privacy\/it\/<\/li>\n \t<li>Chrome: https:\/\/support.google.com\/accounts\/answer\/61416?hl=it<\/li>\n \t<li>Opera: http:\/\/www.opera.com\/help\/tutorials\/security\/cookies\/<\/li>\n<\/ul>\n<h4>5 \u2013 Plugin Social Network<\/h4>\nIl presente sito incorpora anche plugin e\/o bottoni per i social network, al fine di consentire una facile condivisione dei contenuti sui vostri social network preferiti. Tali plugin sono programmati in modo da non impostare alcun cookie all\u2019accesso della pagina, per salvaguardare la privacy degli utenti. Eventualmente i cookie vengono impostati, se cos\u00ec previsto dai social network, solo quando l\u2019utente fa effettivo e volontario uso del plugin. Si tenga presente che se l\u2019utente naviga essendo loggato nel social network allora ha gi\u00e0 acconsentito all\u2019uso dei cookie veicolati tramite questo sito al momento dell\u2019iscrizione al social network.\nLa raccolta e l\u2019uso delle informazioni ottenute a mezzo del plugin sono regolati dalle rispettive informative privacy dei social network, alle quali si prega di fare riferimento:\n<ul>\n \t<li>Facebook: https:\/\/www.facebook.com\/help\/cookies<\/li>\n \t<li>Twitter: https:\/\/support.twitter.com\/articles\/20170519-uso-dei-cookie-e-di-altre-tecnologie-simili-da-parte-di-twitter<\/li>\n \t<li>Google+:http:\/\/www.google.com\/policies\/technologies\/cookies<\/li>\n \t<li>Pinterest: https:\/\/about.pinterest.com\/it\/privacy-policy<\/li>\n \t<li>AddThis: http:\/\/www.addthis.com\/privacy\/privacy-policy<\/li>\n \t<li>Linkedin: https:\/\/www.linkedin.com\/legal\/cookie-policy<\/li>\n<\/ul>\n<h3>DIRITTI DELL\u2019UTENTE<\/h3>\nL\u2019art. 13, c. 2 del Regolamento UE 2016\/679 elenca i diritti dell\u2019utente.\nIl sito Sito web Nida\u2019s intende pertanto informare l\u2019utente sull\u2019esistenza:\n<ul>\n \t<li>del diritto dell\u2019interessato di chiedere al titolare l\u2019accesso ai dati personali (art. 15 Regolamento UE), il loro aggiornamento (art. 7, co. 3, lett. a) D.Lgs. 196\/2003), la rettifica (art. 16 Regolamento UE), l\u2019integrazione (art. 7, co. 3, lett. a) D.Lgs. 196\/2003) o la limitazione del trattamento che lo riguardino (art. 18 Regolamento UE) o di opporsi, per motivi legittimi, al loro trattamento (art. 21 Regolamento UE), oltre al diritto alla portabilit\u00e0 dei dati (art. 20 Regolamento UE);<\/li>\n \t<li>del diritto di chiedere la cancellazione (art. 17 Regolamento UE), la trasformazione in forma anonima o il blocco dei dati trattati in violazione di legge, compresi quelli di cui non \u00e8 necessaria la conservazione in relazione agli scopi per i quali i dati sono stati raccolti o successivamente trattati (art. 7, co. 3, lett. b) D.Lgs. 196\/2003);<\/li>\n \t<li>del diritto di ottenere l\u2019attestazione che le operazioni di aggiornamento, rettificazione, integrazione dei dati, cancellazione, blocco dei dati, trasformazione sono state portate a conoscenza, anche per quanto riguarda il loro contenuto, di coloro ai quali i dati sono stati comunicati o diffusi, eccettuato il caso in cui tale adempimento si rivela impossibile o comporta un impiego di mezzi manifestamente sproporzionato rispetto al diritto tutelato (art. 7, co. 3, lett. C) D.lgs. 196\/2003);<\/li>\n<\/ul>\nLe richieste possono essere indirizzate al titolare del trattamento, senza formalit\u00e0 o, in alternativa, utilizzando il modello previsto dal Garante per la Protezione dei Dati Personali, o inviando una mail all\u2019indirizzo: info@nidas.it.\n\nQualora il trattamento sia basato sull\u2019art. 6, paragrafo 1, lett. a) \u2013 consenso espresso all\u2019utilizzo \u2013 oppure sull\u2019art. 9, paragrafo 2 lett. a) \u2013 consenso espresso all\u2019utilizzo di dati genetici, biometrici, relativi alla salute, che rivelino convinzioni religiose, o filosofiche o appartenenza sindacale, che rivelino l\u2019origine razziale o etnica, le opinioni politiche \u2013 l\u2019utente ha il diritto di revocare il consenso in qualsiasi momento senza pregiudicare la liceit\u00e0 del trattamento basata sul consenso prestato prima della revoca.\n\nParimenti, in caso di violazione della normativa, l\u2019utente ha il diritto di proporre reclamo presso il Garante per la Protezione dei Dati Personali, quale autorit\u00e0 preposta al controllo sul trattamento nello Stato Italiano.\n\nPer una disamina pi\u00f9 approfondita dei diritti che Le competono, si vedano gli artt. 15 e ss. del Regolamento UE 2016\/679 e l\u2019art. 7 del D.Lgs. 196\/2003.\n<h3>VI \u2013 TRASFERIMENTO DATI A PAESI EXTRA UE<\/h3>\nIl presente sito potrebbe condividere alcuni dei dati raccolti con servizi localizzati al di fuori dell\u2019area dell\u2019Unione Europea. In particolare con Google, Facebook e Microsoft (LinkedIn) tramite i social plugin e il servizio di Google Analytics. Il trasferimento \u00e8 autorizzato e strettamente regolato dall\u2019articolo 45, comma 1 del Regolamento UE 2016\/679, per cui non occorre ulteriore consenso. Le aziende sopra menzionate garantiscono la propria adesione al Privacy Shield.\nNon verranno mai trasferiti dati a Paesi terzi che non rispettino le condizioni previste dall\u2019articolo 45 e ss, del Regolamento UE.\n<h3>VII - SICUREZZA DATI FORNITI<\/h3>\nIl presente sito tratta i dati degli utenti in maniera lecita e corretta, adottando le opportune misure di sicurezza volte ad impedire accessi non autorizzati, divulgazione, modifica o distruzione non autorizzata dei dati. Il trattamento viene effettuato mediante strumenti informatici e\/o telematici, con modalit\u00e0 organizzative e con logiche strettamente correlate alle finalit\u00e0 indicate.\nOltre al titolare, in alcuni casi, potrebbero avere accesso ai dati categorie di incaricati coinvolti nell\u2019organizzazione del sito (personale amministrativo, commerciale, marketing, legali, amministratori di sistema) ovvero soggetti esterni (come fornitori di servizi tecnici terzi, corrieri postali, hosting provider, societ\u00e0 informatiche, agenzie di comunicazione).\n<h3>VIII - MODIFICHE AL PRESENTE DOCUMENTO<\/h3>\nIl presente documento, pubblicato all\u2019indirizzo: <a href=\"https:\/\/ellegi.com\/privacy-policy\/\">http:\/\/www.nidas.it\/informativa-privacy\/<\/a> costituisce la privacy policy di questo sito.\nEsso pu\u00f2 essere soggetto a modifiche o aggiornamenti. Si invitano gli utenti a consultare periodicamente la presente pagina per essere sempre aggiornati sulle ultime novit\u00e0 legislative.\nLe versioni precedenti del documento saranno comunque consultabili a questa pagina.\nIl documento \u00e8 stato aggiornato in data 21\/05\/2018 per essere conforme alle disposizioni normative in materia, ed in particolare in conformit\u00e0 al Regolamento UE 2016\/679.","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-248514","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/pages\/248514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/comments?post=248514"}],"version-history":[{"count":0,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/pages\/248514\/revisions"}],"wp:attachment":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/media?parent=248514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}