{"id":246172,"date":"2022-07-21T10:13:44","date_gmt":"2022-07-21T08:13:44","guid":{"rendered":"https:\/\/ellegi.com\/?p=246172"},"modified":"2022-07-26T11:07:18","modified_gmt":"2022-07-26T09:07:18","slug":"chiusura-estiva-2022","status":"publish","type":"post","link":"https:\/\/ellegi.com\/it\/2022\/07\/chiusura-estiva-2022\/","title":{"rendered":"Chiusura estiva 2022"},"content":{"rendered":"\n\n\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;1px|auto||auto||&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;2fa55ecb-cc36-458a-bbf1-8a0aeb26e909&#8243; custom_margin=&#8221;0px||1px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"JsGRdQ\"><\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"JsGRdQ\"><\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"JsGRdQ\">Le <\/span><strong><span class=\"JsGRdQ\">vacanze<\/span><\/strong><span class=\"JsGRdQ\"> sono sempre pi\u00f9 vicine!<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"JsGRdQ\">Noi ci prendiamo una <\/span><strong><span class=\"JsGRdQ\">pausa<\/span><span class=\"JsGRdQ\"> <\/span><span class=\"JsGRdQ\">estiva<\/span><\/strong><span class=\"JsGRdQ\">, certi che ad attenderci ci saranno tante splendide sfide da affrontare insieme. Torneremo al lavoro con la stessa <\/span><strong><span class=\"JsGRdQ\">determinazione<\/span><\/strong><span class=\"JsGRdQ\"> e la stessa <\/span><strong><span class=\"JsGRdQ\">passione<\/span><\/strong><span class=\"JsGRdQ\"> di sempre, per garantirvi un <\/span><strong><span class=\"JsGRdQ\">servizio d&#8217;eccellenza<\/span><\/strong><span class=\"JsGRdQ\">!<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><span class=\"JsGRdQ\">Gli <\/span><strong><span class=\"JsGRdQ\">uffici WG Ellegi saranno chiusi da sabato 6 a luned\u00ec 22 agosto compresi<\/span><\/strong><span class=\"JsGRdQ\">. Appuntamento a marted\u00ec 23 per la ripresa abituale delle attivit\u00e0.<\/span><span class=\"JsGRdQ white-space-prewrap\"> <\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><\/p>\n<p class=\"_04xlpA direction-ltr align-start para-style-body\"><strong><span class=\"JsGRdQ\">Buone vacanze da parte di tutto il team!<\/span><\/strong><span class=\"JsGRdQ white-space-prewrap\"> <\/span><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n\n","protected":false},"excerpt":{"rendered":"<p>Noi ci prendiamo una pausa estiva, certi che ad attenderci ci saranno tante splendide sfide da affrontare insieme. Gli uffici WG Ellegi saranno chiusi da sabato 6 a luned\u00ec 22 agosto compresi.<\/p>\n","protected":false},"author":16,"featured_media":246175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-246172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicazioni"],"_links":{"self":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/posts\/246172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/comments?post=246172"}],"version-history":[{"count":0,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/posts\/246172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/media\/246175"}],"wp:attachment":[{"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/media?parent=246172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/categories?post=246172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ellegi.com\/it\/wp-json\/wp\/v2\/tags?post=246172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}